{"id":2892,"date":"2025-02-01T14:36:34","date_gmt":"2025-02-01T13:36:34","guid":{"rendered":"https:\/\/www.bsmn.de\/faks-memmingen\/?p=2892"},"modified":"2025-02-01T14:36:36","modified_gmt":"2025-02-01T13:36:36","slug":"wenn-worte-bilder-zaubern-erzaehlpaedagogin-steffi-krausse-begeistert-angehende-erzieherinnen-und-erzieher","status":"publish","type":"post","link":"https:\/\/www.bsmn.de\/faks-memmingen\/2025\/02\/01\/wenn-worte-bilder-zaubern-erzaehlpaedagogin-steffi-krausse-begeistert-angehende-erzieherinnen-und-erzieher\/","title":{"rendered":"Wenn Worte Bilder zaubern: Erz\u00e4hlp\u00e4dagogin Steffi Krau\u00dfe begeistert angehende Erzieherinnen und Erzieher"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mit nur wenigen Worten weckt Erz\u00e4hlp\u00e4dagogin Steffi Krau\u00dfe die Fantasie ihres Publikums an der Fachakademie f\u00fcr Sozialp\u00e4dagogik Memmingen. In der Faks1 stellt sie ihre wirksamen Methoden mit dem Erz\u00e4hlsackerl und dem Geschichtens\u00e4ckchen vor \u2013 liebevoll gef\u00fcllte Beutel, die Geschichten lebendig werden lassen. Die Studierenden erfahren, wie sie bereits kleine Kinder mithilfe ausgew\u00e4hlter Requisiten behutsam an Sprache heranf\u00fchren k\u00f6nnen. Die Begeisterung war gro\u00df: Denn wenn Geschichten greifbar werden, entfaltet sich eine Zauberwelt, in der Sprache spielerisch erlebt und gelernt wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit nur wenigen Worten weckt Erz\u00e4hlp\u00e4dagogin Steffi Krau\u00dfe die Fantasie ihres Publikums an der Fachakademie f\u00fcr Sozialp\u00e4dagogik Memmingen. In der Faks1 stellt sie ihre wirksamen Methoden mit dem Erz\u00e4hlsackerl und dem Geschichtens\u00e4ckchen vor \u2013 liebevoll gef\u00fcllte Beutel, die Geschichten lebendig werden lassen. Die Studierenden erfahren, wie sie bereits kleine Kinder mithilfe ausgew\u00e4hlter Requisiten behutsam an [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":2893,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.bsmn.de\/faks-memmingen\/wp-json\/wp\/v2\/posts\/2892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bsmn.de\/faks-memmingen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bsmn.de\/faks-memmingen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bsmn.de\/faks-memmingen\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bsmn.de\/faks-memmingen\/wp-json\/wp\/v2\/comments?post=2892"}],"version-history":[{"count":1,"href":"https:\/\/www.bsmn.de\/faks-memmingen\/wp-json\/wp\/v2\/posts\/2892\/revisions"}],"predecessor-version":[{"id":2894,"href":"https:\/\/www.bsmn.de\/faks-memmingen\/wp-json\/wp\/v2\/posts\/2892\/revisions\/2894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bsmn.de\/faks-memmingen\/wp-json\/wp\/v2\/media\/2893"}],"wp:attachment":[{"href":"https:\/\/www.bsmn.de\/faks-memmingen\/wp-json\/wp\/v2\/media?parent=2892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bsmn.de\/faks-memmingen\/wp-json\/wp\/v2\/categories?post=2892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bsmn.de\/faks-memmingen\/wp-json\/wp\/v2\/tags?post=2892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}